{"id":777096235,"date":"2026-07-15T11:08:50","date_gmt":"2026-07-15T14:08:50","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=777096235"},"modified":"2026-07-15T11:20:50","modified_gmt":"2026-07-15T14:20:50","slug":"el-iplyc-misiones-expande-su-trabajo-social-en-la-provincia","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/el-iplyc-misiones-expande-su-trabajo-social-en-la-provincia","title":{"rendered":"El IPLyC Misiones expande su trabajo social en la provincia"},"content":{"rendered":"\n<p>El equipo del programa social inclusivo del organismo entreg\u00f3 material educativo en la Escuela Especial 38 \u201cJes\u00fas Ni\u00f1o\u201d en Santo Pip\u00f3, y la iniciativa Mirar Mejor lleg\u00f3 a Puerto Leoni.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p>Argentina.- El Instituto Provincial de Loter\u00eda y Casinos (<a href=\"https:\/\/focusgn.com\/latinoamerica\/el-iplyc-misiones-presento-la-red-de-asistencia-comercial-para-potenciar-las-ventas\" target=\"_blank\" rel=\"noreferrer noopener\">IPLyC Misiones<\/a>) inform\u00f3 que su equipo del programa social inclusivo entreg\u00f3 <strong>material educativo<\/strong> a la comunidad de la Escuela Especial 38 \u201cJes\u00fas Ni\u00f1o\u201d, del barrio El Mirador, en Santo Pip\u00f3. Por otra parte, vecinos de Puerto Leoni accedieron al <strong>programa Mirar Mejor<\/strong>.<\/p>\n\n\n\n<p>Durante la visita a la escuela de Santo Pip\u00f3, que cuenta con una veintena de alumnos, representantes del organismo entregaron un kit con elementos para la actividad f\u00edsica y motricidad, aprendizaje y cognici\u00f3n, ingenio y construcci\u00f3n, adem\u00e1s de un juego sensorial y l\u00fadico. El material ser\u00e1 utilizado en las tareas del aula y de entretenimiento con los estudiantes.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"900\" height=\"506\" src=\"https:\/\/focusgn.com\/latinoamerica\/wp-content\/uploads\/sites\/2\/2026\/07\/Inclusivo-Escuela-especial-38-Santo-Pipo-2-900x506.jpeg\" alt=\"\" class=\"wp-image-777096245\" srcset=\"https:\/\/focusgn.com\/latinoamerica\/wp-content\/uploads\/sites\/2\/2026\/07\/Inclusivo-Escuela-especial-38-Santo-Pipo-2-900x506.jpeg 900w, https:\/\/focusgn.com\/latinoamerica\/wp-content\/uploads\/sites\/2\/2026\/07\/Inclusivo-Escuela-especial-38-Santo-Pipo-2-300x169.jpeg 300w, https:\/\/focusgn.com\/latinoamerica\/wp-content\/uploads\/sites\/2\/2026\/07\/Inclusivo-Escuela-especial-38-Santo-Pipo-2.jpeg 1280w\" sizes=\"auto, (max-width: 900px) 100vw, 900px\" \/><\/figure>\n\n\n\n<p>La directora del establecimiento, Lissa Saya, indic\u00f3 que \u201clo que nos traen es de fundamental importancia para el trabajo que se realiza d\u00eda a d\u00eda, sobre todo en la parte de actividades did\u00e1cticas y herramientas adaptadas\u201d.<\/p>\n\n\n\n<p>En tanto, <strong>centenares de vecinos de Puerto Leoni accedieron al programa Mirar Mejor<\/strong>, una iniciativa del Gobierno de Misiones, coordinada por el IPLyC, en conjunto con la Sociedad de Oftalmolog\u00eda de Misiones (SOMI). La iniciativa se llev\u00f3 a cabo en la Municipalidad y cont\u00f3 con una gran concurrencia. La propuesta incluy\u00f3 la entrega de recetas de anteojos.<\/p>\n\n\n\n<p>El presidente del IPLyC, <strong>H\u00e9ctor Rojas Decut<\/strong>, afirm\u00f3: \u201cLa pol\u00edtica p\u00fablica cobra sentido cuando llega a las personas. Estar cerca significa escuchar, recorrer y transformar necesidades en respuestas concretas\u201d. Luego agreg\u00f3: \u201cComo instituci\u00f3n de la provincia, entendemos que es nuestra responsabilidad: trabajamos para generar oportunidades y mejorar la calidad de vida de los misioneros\u201d.<\/p>\n\n\n\n<p>Con <strong>21 localidades recorridas en lo que va del a\u00f1o<\/strong>, el programa Mirar Mejor sigue sumando destinos para llevar la atenci\u00f3n oftalmol\u00f3gica integral a diferentes comunas de la provincia de Misiones.<\/p>\n\n\n<div id=\"see-also-container\"><span class=\"see-also-label\">Ver tambi\u00e9n:<\/span>\n<div class=\"related-article\"><img decoding=\"async\" class=\"related-article__thumbnail\" src=\"https:\/\/focusgn.com\/latinoamerica\/wp-content\/uploads\/sites\/2\/2026\/06\/WhatsApp-Image-2026-06-03-at-15.21.28-1-1024x768-1-267x200.jpeg\" alt=\"\" \/>\n<p class=\"related-article__text\"><span class=\"see-also-label-strong\">Ver tambi\u00e9n:<\/span> <a href=\"https:\/\/focusgn.com\/latinoamerica\/el-iplyc-de-misiones-llevo-adelante-una-nueva-jornada-de-mirar-mejor\">El IPLyC Misiones llev\u00f3 adelante una nueva jornada de Mirar Mejor<\/a><\/p>\n<\/div>\n<\/div>","protected":false},"excerpt":{"rendered":"<p>El equipo del programa social inclusivo del organismo entreg\u00f3 material educativo en la Escuela Especial 38 \u201cJes\u00fas Ni\u00f1o\u201d en Santo Pip\u00f3, y la iniciativa Mirar Mejor lleg\u00f3 a Puerto Leoni.<\/p>\n","protected":false},"author":218,"featured_media":74213,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"El Instituto Provincial de Loter\u00eda y Casinos (IPLyC Misiones) ha implementado programas de responsabilidad social en la provincia de Misiones, Argentina. Estos incluyen la entrega de material educativo a una escuela especial en Santo Pip\u00f3 y la provisi\u00f3n de atenci\u00f3n oftalmol\u00f3gica a trav\u00e9s del programa \"Mirar Mejor\" en Puerto Leoni. Estas iniciativas subrayan el compromiso del organismo con la mejora de la calidad de vida y la aplicaci\u00f3n de pol\u00edticas p\u00fablicas.","focusai_entities":"Instituto Provincial de Loter\u00eda y Casinos (IPLyC Misiones), Escuela Especial 38 \u201cJes\u00fas Ni\u00f1o\u201d, Sociedad de Oftalmolog\u00eda de Misiones (SOMI), H\u00e9ctor Rojas Decut, Lissa Saya","focusai_location":"Argentina, Misiones, Santo Pip\u00f3, Puerto Leoni","focusai_target_profile":"ceo_executive (0.7), regulator (0.9), compliance_legal (0.7), operator_casino (0.7), investor_analyst (0.7), journalist_researcher (0.9)","focusai_suggestions":[{"label":"Estrategia ESG IPLyC","query":"\u00bfC\u00f3mo se alinean estas iniciativas de responsabilidad social con una estrategia ESG m\u00e1s amplia del IPLyC Misiones, y qu\u00e9 m\u00e9tricas se utilizan para evaluar su impacto en la licencia social y la percepci\u00f3n p\u00fablica?"},{"label":"Financiaci\u00f3n y Gobernanza","query":"\u00bfCu\u00e1l es la estructura de financiaci\u00f3n de estos programas sociales y c\u00f3mo se garantiza la transparencia y la gobernanza en la asignaci\u00f3n de fondos derivados de la operaci\u00f3n de juegos de azar?"}],"footnotes":""},"categories":[287,10],"tags":[41,34055],"class_list":["post-777096235","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-sociales","category-sudamerica","tag-argentina","tag-iplyc-de-misiones"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777096235","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/218"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=777096235"}],"version-history":[{"count":6,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777096235\/revisions"}],"predecessor-version":[{"id":777096246,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777096235\/revisions\/777096246"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media\/74213"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=777096235"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=777096235"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=777096235"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}