{"id":777086692,"date":"2026-04-13T10:44:23","date_gmt":"2026-04-13T13:44:23","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=777086692"},"modified":"2026-04-29T20:29:40","modified_gmt":"2026-04-29T23:29:40","slug":"aragon-lanza-subenciones-para-la-prevencion-del-juego-patologico","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/aragon-lanza-subenciones-para-la-prevencion-del-juego-patologico","title":{"rendered":"Arag\u00f3n lanza subenciones para la prevenci\u00f3n del juego patol\u00f3gico"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El Gobierno destina EUR 60.000 a entidades sociales para financiar proyectos de informaci\u00f3n y prevenci\u00f3n de la ludopat\u00eda.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Espa\u00f1a.- El Departamento de Hacienda, Interior y Administraci\u00f3n P\u00fablica de <a href=\"https:\/\/focusgn.com\/latinoamerica\/el-pp-publico-el-reglamento-general-del-juego-de-aragon\" target=\"_blank\" rel=\"noreferrer noopener\">Arag\u00f3n<\/a> convoc\u00f3 una nueva l\u00ednea de subvenciones orientada a reforzar la prevenci\u00f3n y la informaci\u00f3n sobre el juego patol\u00f3gico. La medida se formaliz\u00f3 a trav\u00e9s de la <strong>Orden HAP\/538\/2026<\/strong>, publicada el 13 de abril en el <strong>Bolet\u00edn Oficial de Arag\u00f3n (BOA)<\/strong>, y cuenta con una inversi\u00f3n de <strong>EUR 60.000 <\/strong>destinada a entidades sin fines de lucro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La convocatoria establece que las ayudas cubrir\u00e1n hasta el <strong>80 por ciento del costo total de las actividades<\/strong>, y las organizaciones deber\u00e1n cubrir el 20 por ciento restante. Se financiar\u00e1n gastos de personal especializado, como m\u00e9dicos y psic\u00f3logos, alquiler de locales y programas de atenci\u00f3n directa e informativa. Las acciones deber\u00e1n desarrollarse durante el 2026 y concluir antes del 15 de noviembre.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La concesi\u00f3n se realizar\u00e1 por <strong>concurrencia competitiva<\/strong>, priorizando la calidad t\u00e9cnica y el alcance de los proyectos. Se otorgar\u00e1 mayor puntuaci\u00f3n a las entidades aut\u00f3nomas y a aquellas que extiendan sus actividades a las 33 capitales de comarca y las tres capitales de provincia. Tambi\u00e9n ser\u00e1 obligatoria la incorporaci\u00f3n de la <strong>perspectiva de g\u00e9nero<\/strong>, con datos espec\u00edficos por sexo, y se valorar\u00e1 la experiencia previa en la gesti\u00f3n de programas similares.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El plazo para presentar solicitudes es de <strong>diez d\u00edas h\u00e1biles<\/strong> a partir del 14 de abril. Todo el procedimiento se llevar\u00e1 a cabo de manera online a trav\u00e9s de la sede del Gobierno de Arag\u00f3n, que dispondr\u00e1 de tres meses para tener una resoluci\u00f3n. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Con esta iniciativa, el Ejecutivo busca consolidar un marco de apoyo institucional que permita a las organizaciones sociales <strong>ampliar su capacidad de acci\u00f3n <\/strong>frente a la ludopat\u00eda y garantizar que la prevenci\u00f3n y la informaci\u00f3n lleguen de forma homog\u00e9nea a todo el territorio.<\/p>\n\r\n\t\t<div id=\"see-also-container\">\r\n\t\t\t<span class=\"see-also-label\">Ver tambi\u00e9n:<\/span>\r\n\t\t\t<div class=\"related-article\">\r\n\t\t\t\t<img decoding=\"async\" class=\"related-article__thumbnail\" src=\"https:\/\/focusgn.com\/latinoamerica\/wp-content\/uploads\/sites\/2\/2026\/03\/a25bb7df-424c-45d1-b58d-985e4aca403d-300x200.jpg\" alt=\"\">\r\n\t\t\t\t<p class=\"related-article__text\">\r\n\t\t\t\t\t<span class=\"see-also-label-strong\">Ver tambi\u00e9n:<\/span> <a href='https:\/\/focusgn.com\/latinoamerica\/el-ministerio-de-consumo-espanol-alerta-sobre-el-incremento-de-mujeres-jovenes-que-apuestan-online'>El Ministerio de Consumo espa\u00f1ol alerta sobre el incremento de mujeres j\u00f3venes que apuestan online<\/a>\r\n\t\t\t\t<\/p>\r\n\t\t\t<\/div>\r\n\t\t<\/div>\r\n\t","protected":false},"excerpt":{"rendered":"<p>El Gobierno destina EUR 60.000 a entidades sociales para financiar proyectos de informaci\u00f3n y prevenci\u00f3n de la ludopat\u00eda.<\/p>\n","protected":false},"author":2384,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"El Gobierno de Arag\u00f3n ha destinado EUR 60.000 en subvenciones para entidades sociales sin fines de lucro, con el objetivo de financiar proyectos de prevenci\u00f3n e informaci\u00f3n sobre la ludopat\u00eda. La iniciativa, formalizada mediante la Orden HAP\/538\/2026, busca reforzar el marco de apoyo institucional y asegurar una cobertura homog\u00e9nea en todo el territorio. La concesi\u00f3n se realizar\u00e1 por concurrencia competitiva, priorizando la calidad t\u00e9cnica, el alcance territorial y la incorporaci\u00f3n de la perspectiva de g\u00e9nero en los proyectos.","focusai_entities":"Gobierno de Arag\u00f3n, Departamento de Hacienda, Interior y Administraci\u00f3n P\u00fablica de Arag\u00f3n, Ministerio de Consumo espa\u00f1ol","focusai_location":"Espa\u00f1a, Arag\u00f3n","focusai_target_profile":"ceo_executive (0.9), regulator (1.0), compliance_legal (0.9), operator_casino (0.8), affiliate_publisher (0.7), product_ux (0.7), marketing_crm (0.7), investor_analyst (0.8), gambler_consumer (0.9), supplier_vendor (0.7), journalist_researcher (1.0)","focusai_suggestions":[],"footnotes":""},"categories":[2,287],"tags":[47,11,38094,38095],"class_list":["post-777086692","post","type-post","status-publish","format-standard","hentry","category-emea","category-sociales","tag-apuestas","tag-espana","tag-prevencion-de-ludopatia","tag-subvenciones"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777086692","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/2384"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=777086692"}],"version-history":[{"count":2,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777086692\/revisions"}],"predecessor-version":[{"id":777086721,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777086692\/revisions\/777086721"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=777086692"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=777086692"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=777086692"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}