{"id":777086546,"date":"2026-04-10T09:17:08","date_gmt":"2026-04-10T12:17:08","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=777086546"},"modified":"2026-04-29T15:45:13","modified_gmt":"2026-04-29T18:45:13","slug":"chile-operativo-contra-el-juego-ilegal-en-galvarino-deja-seis-detenidos","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/chile-operativo-contra-el-juego-ilegal-en-galvarino-deja-seis-detenidos","title":{"rendered":"Clausuran un casino ilegal en Galvarino, Chile: hay seis detenidos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La PDI incaut\u00f3 48 m\u00e1quinas de azar valuadas en m\u00e1s de US$30.000 y dinero en efectivo en una casa de apuestas que ya hab\u00eda sido clausurada en 2023.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Chile.- Seis personas, cinco de nacionalidad chilena y una ciudadana china en situaci\u00f3n migratoria irregular, fueron detenidas en <strong>Galvarino, regi\u00f3n de La Araucan\u00eda<\/strong>, durante un operativo de la <strong>Polic\u00eda de Investigaciones (PDI)<\/strong>. El procedimiento se realiz\u00f3 en un inmueble ubicado en la calle Ram\u00f3n Freire que funcionaba como casino clandestino, pese a haber sido clausurado por el municipio tres a\u00f1os atr\u00e1s.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan inform\u00f3 el medio local Radio Bio Bio, el subprefecto <strong>Pedro Honorato Salvo<\/strong>, jefe de la <strong>Brigada de Investigaci\u00f3n Criminal (BICRIM)<\/strong> de <a href=\"https:\/\/focusgn.com\/latinoamerica\/operativo-en-chile-incautan-mas-de-100-maquinas-ilegales-en-un-casino-clandestino-en-lautaro\" target=\"_blank\" rel=\"noreferrer noopener\">Lautaro<\/a>, explic\u00f3: \u201cEn coordinaci\u00f3n con el Ministerio P\u00fablico, se gestion\u00f3 la respectiva orden judicial de entrada y registro, logrando la detenci\u00f3n de seis personas en situaci\u00f3n de flagrancia. Adem\u00e1s, se incautaron diversas m\u00e1quinas de juego y dinero en efectivo\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La diligencia fue encabezada por la <strong>BICRIM<\/strong>, en coordinaci\u00f3n con la <strong>Fiscal\u00eda Local<\/strong>, y permiti\u00f3 la incautaci\u00f3n de <strong>48 m\u00e1quinas de juegos de azar<\/strong>, valuadas en m\u00e1s de <strong>CLP 29 m (US$30.000)<\/strong>, adem\u00e1s de dinero en efectivo obtenido a trav\u00e9s de las ganancias il\u00edcitas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las investigaciones confirmaron que el recinto operaba con alta concurrencia de p\u00fablico y obten\u00eda ganancias sin contar con autorizaci\u00f3n municipal ni de la <strong>Superintendencia de Casinos de Juego<\/strong>. Respecto al ciudadano chino,&nbsp;se adoptaron adem\u00e1s las acciones administrativas correspondientes por infracci\u00f3n a la <strong>Ley de Migraci\u00f3n y Extranjer\u00eda<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los detenidos quedaron a disposici\u00f3n del <strong>Ministerio P\u00fablico<\/strong>, para ser presentados ante el <strong>Juzgado de Garant\u00eda de Lautaro<\/strong>, con jurisdicci\u00f3n en Galvarino. El operativo cont\u00f3 con apoyo de personal municipal y de seguridad p\u00fablica, reforzando el accionar institucional para combatir de manera exitosa el juego ilegal en la regi\u00f3n.<\/p>\n\n\n<div id=\"see-also-container\">\n\t\t\t<span class=\"see-also-label\">Ver tambi\u00e9n:<\/span><\/p>\n<div class=\"related-article\">\n\t\t\t\t<img decoding=\"async\" class=\"related-article__thumbnail\" src=\"https:\/\/focusgn.com\/latinoamerica\/wp-content\/uploads\/sites\/2\/2023\/12\/enjoy-antofagasta-300x160.jpg\" alt=\"\"><\/p>\n<p class=\"related-article__text\">\n\t\t\t\t\t<span class=\"see-also-label-strong\">Ver tambi\u00e9n:<\/span> <a href='https:\/\/focusgn.com\/latinoamerica\/casino-de-antofagasta-socios-enfrentados-por-deudas-y-la-propiedad-del-inmueble'>Casino de Antofagasta: socios enfrentados por deudas y la propiedad del inmueble<\/a>\n\t\t\t\t<\/p>\n<\/p><\/div>\n<\/p><\/div>","protected":false},"excerpt":{"rendered":"<p>La PDI incaut\u00f3 48 m\u00e1quinas de azar valuadas en m\u00e1s de US$30.000 y dinero en efectivo en una casa de apuestas que ya hab\u00eda sido clausurada en 2023.<\/p>\n","protected":false},"author":2384,"featured_media":777086571,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"La PDI incaut\u00f3 48 m\u00e1quinas de azar y dinero en efectivo en un casino clandestino en Galvarino, Chile, que operaba sin autorizaci\u00f3n y hab\u00eda sido clausurado previamente en 2023. Se detuvo a seis personas, incluyendo un ciudadano chino en situaci\u00f3n irregular, en un operativo coordinado con el Ministerio P\u00fablico, reforzando la acci\u00f3n institucional contra el juego ilegal.","focusai_entities":"PDI, Ministerio P\u00fablico, Radio Bio Bio, Pedro Honorato Salvo, BICRIM Lautaro, Superintendencia de Casinos de Juego, Juzgado de Garant\u00eda de Lautaro","focusai_location":"Chile, Galvarino, La Araucan\u00eda, Lautaro","focusai_target_profile":"ceo_executive (0.8), regulator (1.0), compliance_legal (0.9), operator_casino (0.8), investor_analyst (0.7), supplier_vendor (0.7), journalist_researcher (0.9)","focusai_suggestions":[],"footnotes":""},"categories":[36,10],"tags":[2400,4461,90],"class_list":["post-777086546","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legales","category-sudamerica","tag-apuestas-ilegales","tag-casinos-ilegales","tag-chile"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777086546","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/2384"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=777086546"}],"version-history":[{"count":4,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777086546\/revisions"}],"predecessor-version":[{"id":777086624,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777086546\/revisions\/777086624"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media\/777086571"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=777086546"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=777086546"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=777086546"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}