{"id":777047966,"date":"2024-11-26T11:08:30","date_gmt":"2024-11-26T14:08:30","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=777047966"},"modified":"2026-04-29T14:22:04","modified_gmt":"2026-04-29T17:22:04","slug":"modificacion-del-proyecto-de-ley-de-ludopatia-y-juego-online-expectativa-por-la-sesion-en-diputados-de-este-miercoles-27-de-noviembre","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/modificacion-del-proyecto-de-ley-de-ludopatia-y-juego-online-expectativa-por-la-sesion-en-diputados-de-este-miercoles-27-de-noviembre","title":{"rendered":"Modificaci\u00f3n del proyecto de ley de ludopat\u00eda y juego online: expectativa por la sesi\u00f3n en Diputados de este mi\u00e9rcoles 27 de noviembre"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Uno de los focos de discusi\u00f3n en el que no se logra consenso es el de la publicidad de las casas de apuestas.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Argentina.- Crece la expectativa en el sector del juego ante el <a href=\"https:\/\/focusgn.com\/latinoamerica\/proyecto-contra-la-ciberludopatia-en-argentina-la-camara-de-diputados-podria-sesionar-la-proxima-semana\" target=\"_blank\" rel=\"noreferrer noopener\">inminente tratamiento<\/a> del proyecto de ley que tiene como objetivo la prevenci\u00f3n de la ludopat\u00eda, la regulaci\u00f3n de juegos de azar y apuestas online y las restricciones publicitarias. El presidente de la<strong> C\u00e1mara de Diputados<\/strong>, <strong>Mart\u00edn Menem<\/strong>, convoc\u00f3 a los legisladores para una sesi\u00f3n el este mi\u00e9rcoles 27 de noviembre a las 12 horas, tras una solicitud de la diputada M\u00f3nica Frade (Coalici\u00f3n C\u00edvica).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La sesi\u00f3n es impulsada por la Coalici\u00f3n C\u00edvica, Encuentro Federal y Radicales para Siempre, y busca darle tratamiento a los <a href=\"https:\/\/focusgn.com\/latinoamerica\/que-dicen-los-dictamenes-sobre-regulacion-de-apuestas-en-linea-y-prevencion-de-la-ludopatia-y-alcanzados-en-diputados\" data-type=\"link\" data-id=\"https:\/\/focusgn.com\/latinoamerica\/que-dicen-los-dictamenes-sobre-regulacion-de-apuestas-en-linea-y-prevencion-de-la-ludopatia-y-alcanzados-en-diputados\" target=\"_blank\" rel=\"noreferrer noopener\">proyectos que obtuvieron dict\u00e1menes<\/a> luego de que cinco bloques opositores de la C\u00e1mara acordaran unificar varias iniciativas contra la industria, para crear un proyecto conjunto. Por el momento, la propuesta obtuvo la aprobaci\u00f3n de las comisiones de Prevenci\u00f3n de Adicciones y Control del Narcotr\u00e1fico; Acci\u00f3n Social y Salud P\u00fablica; Comunicaciones e Inform\u00e1tica; Legislaci\u00f3n Penal; y Familias, Ni\u00f1ez y Juventudes.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, todav\u00eda existen intensas discusiones que complicar\u00edan el avance del proyecto, ya que a\u00fan tampoco hay garant\u00edas de qu\u00f3rum. Pero, una vez superado el conflicto sobre el n\u00famero de qu\u00f3rum, si avanza la sesi\u00f3n, se espera un fuerte debate respecto del <strong>art\u00edculo que se refiere a las restricciones de la publicidad, promoci\u00f3n y patrocinio del juego online<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El dictamen de mayor\u00eda se basa en un&nbsp;<a href=\"https:\/\/focusgn.com\/latinoamerica\/presentan-un-nuevo-proyecto-para-limitar-la-publicidad-del-juego-y-las-apuestas-en-argentina\" target=\"_blank\" rel=\"noreferrer noopener\">proyecto de Maximiliano Ferraro<\/a>&nbsp;de la Coalici\u00f3n C\u00edvica, y otras iniciativas de&nbsp;Uni\u00f3n por la Patria (UxP), Encuentro Federal y los radicales de \u00abDemocracia para Siempre\u00bb, mientras que La Libertad Avanza, el PRO, y la UCR presentaron un dictamen de minor\u00eda en base a un&nbsp;<a href=\"https:\/\/focusgn.com\/latinoamerica\/argentina-nuevo-proyecto-de-ley-para-regular-la-publicidad-y-el-acceso-al-juego-online\" target=\"_blank\" rel=\"noreferrer noopener\">proyecto de Silvana Giudici<\/a>.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">Los proyectos punto por punto<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">El elemento diferenciador entre uno y otro dictamen est\u00e1 en este caso en el art\u00edculo 8\u00b0 que figura en el proyecto de dictamen respaldado por la mayor\u00eda,&nbsp;<strong>referido a la prohibici\u00f3n de la publicidad, promoci\u00f3n y patrocinio de los juegos de azar, de pron\u00f3sticos y apuestas deportivas y de apuestas en l\u00ednea<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quedan comprendidas las plataformas y redes sociales a trav\u00e9s de Internet, las tecnolog\u00edas de la informaci\u00f3n y la comunicaci\u00f3n, la comunicaci\u00f3n audiovisual, la publicidad exterior, la carteler\u00eda en la v\u00eda p\u00fablica o en espacios privados de uso p\u00fablico, medios de difusi\u00f3n gr\u00e1fica, radiales, televisivos, emplazamiento del producto, podcast o cualquier otro medio de comunicaci\u00f3n actual o que surja en el futuro.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El proyecto estipula que quedan prohibidos los bonos de bienvenida de juegos de azar y apuestas en l\u00ednea, como tambi\u00e9n el auspicio de equipos deportivos o deportistas en forma individual, utilizar su marca o denominaci\u00f3n comercial para identificar a una instalaci\u00f3n deportiva, estadios, academias deportivas, centros recreativos, espacios p\u00fablicos, centros de entrenamiento, la promoci\u00f3n de pron\u00f3sticos deportivos y la colocaci\u00f3n de carteler\u00eda fija o digital en los campos de juego y estadios. Tambi\u00e9n su difusi\u00f3n en festivales o recitales art\u00edsticos o musicales y eventos culturales en general.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo queda prohibida la publicidad no tradicional (PNT) de los juegos de azar, de pron\u00f3sticos y apuestas deportivas y de apuestas online -definida en la<strong>\u00a0Ley de Servicios de Comunicaci\u00f3n Audiovisual N\u00b0 26.552<\/strong>-; la publicidad indirecta o encubierta en la que se haga menci\u00f3n a los juegos de azar, de pron\u00f3sticos y apuestas deportivas y apuestas online a trav\u00e9s de influencers, de programas infomerciales y\/o la publicaci\u00f3n onerosa o no, de testimonios de deportistas, personajes famosos, figuras de relevancia p\u00fablica o personajes de ficci\u00f3n, que los mencione.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su art\u00edculo 10\u00b0, este dictamen establece la<strong>\u00a0verificaci\u00f3n biom\u00e9trica de identidad y edad<\/strong>. Los operadores\/licenciatarios de la explotaci\u00f3n de juegos de apuestas online deben poseer en sus sitios, aplicaciones o p\u00e1ginas web, mecanismos, herramientas y filtros que garanticen en forma fehaciente la imposibilidad de acceso de menores de edad. A tal efecto, deben utilizar Sistemas de Identidad Digital (SID) conectados con la base de datos del\u00a0<strong>Registro Nacional de las Personas (RENAPER)<\/strong>\u00a0para validar la identidad a distancia, mediante el reconocimiento facial.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La comercializaci\u00f3n y\/o distribuci\u00f3n y\/o expendio de juegos de azar y de apuestas online, debe cumplir con las exigencias de juego responsable. Por ejemplo, proporcionar al usuario apostador informaci\u00f3n precisa, completa y veraz respecto del tipo de juego online, reglas, probabilidad de obtener premios y dem\u00e1s informaci\u00f3n relacionada a la operatoria de juego.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Debe disponer de una indicaci\u00f3n visible de la herramienta de asistencia a personas con ludopat\u00eda dispuesto por la\u00a0<strong>Autoridad de Aplicaci\u00f3n<\/strong>. Asimismo disponer de mecanismos de identificaci\u00f3n y prohibici\u00f3n de juego online, a personas inscriptas en el ReNA. Se debe adem\u00e1s establecer un sistema de registro y logueo para impedir el acceso de ni\u00f1os, ni\u00f1as y adolescentes, conforme la presente norma.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ver tambi\u00e9n:<\/strong>&nbsp;<a href=\"https:\/\/focusgn.com\/latinoamerica\/encuesta-en-escuelas-secundarias-revela-que-1-de-cada-4-jovenes-de-la-ciudad-de-buenos-aires-hizo-una-apuesta-online-al-menos-una-vez\" target=\"_blank\" rel=\"noreferrer noopener\">Encuesta en escuelas secundarias revela que 1 de cada 4 j\u00f3venes de la Ciudad de Buenos Aires hizo una apuesta online al menos una vez<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los operadores\/licenciatarios de la explotaci\u00f3n de sitios de juegos de azar y apuestas online deber\u00e1n incluir las siguientes leyendas de advertencia en las interfaces de acceso y uso. En la pantalla de inicio, ocupando no menos del 50 por ciento de la totalidad de la pantalla: \u201cEst\u00e1 prohibida la participaci\u00f3n de menores de edad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, hay un art\u00edculo dedicado a las\u00a0<strong>prohibiciones especiales<\/strong>. All\u00ed se proh\u00edbe a los sitios y\/o plataformas de juego azar y apuestas online, la implementaci\u00f3n de acciones de fidelizaci\u00f3n o que ofrezcan juegos online en la modalidad de opciones binarias y en la modalidad de micro transacciones o juegos de bot\u00edn o las que incluyeran las siguientes estrategias de gamificaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">No podr\u00e1n ser apostadores en sitios o plataformas de juegos de azar y apuestas online los accionistas, propietarios, part\u00edcipes o titulares del operador de juego, su personal directivo y empleados directamente involucrados en el desarrollo de los juegos de azar y apuestas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Tampoco los deportistas, entrenadores u otros participantes directos en el acontecimiento o actividad deportiva sobre la que se realiza la apuesta. Los jueces o \u00e1rbitros que ejerzan sus funciones en el acontecimiento o actividad deportiva sobre la que se realiza la apuesta, as\u00ed como las personas que resuelven los recursos contra las decisiones de aquellos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Los registrados en el&nbsp;<strong>R\u00e9gimen Nacional de Autoexclusi\u00f3n (ReNA)<\/strong>&nbsp;y quienes est\u00e9n registrados en reg\u00edmenes de autoexclusi\u00f3n provinciales y de la Ciudad Aut\u00f3noma de Buenos Aires.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En su art\u00edculo 21\u00b0, el dictamen propone el\u00a0<strong>bloqueo de plataformas no autorizadas<\/strong>. Ante la existencia de denuncias tramitadas por la Autoridad de Aplicaci\u00f3n u otras personas humanas o jur\u00eddicas, el juzgado competente podr\u00e1 disponer en tr\u00e1mite sumar\u00edsimo el bloqueo de los sitios web en que se realicen oferta de Juegos de azar online no autorizados, que no cumplan con el dominio cuya denominaci\u00f3n sea \u201cbet.ar\u201d y\/o aquella que la reemplace; o la suspensi\u00f3n preventiva de las plataformas de juegos de azar online autorizadas que incumplan disposiciones contenidas en la presente ley.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la&nbsp;<strong>regulaci\u00f3n de medios de pago<\/strong>, se establece a las tarjetas de d\u00e9bito bancarias, sujetas a un l\u00edmite diario equivalente al tope o l\u00edmite de extracci\u00f3n diario establecido por la entidad bancaria o financiera para los cajeros autom\u00e1ticos; las billeteras electr\u00f3nicas \/ virtuales solo con dinero en cuenta y sujetas a un l\u00edmite diario equivalente al tope o l\u00edmite de extracci\u00f3n diario establecido por la entidad bancaria o financiera para los cajeros autom\u00e1ticos. No podr\u00e1n ser utilizadas con la funci\u00f3n cr\u00e9dito: las cuentas ANSeS; las tarjetas de cr\u00e9dito.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto al&nbsp;<strong>r\u00e9gimen sancionatorio<\/strong>, el incumplimiento de las disposiciones o transgresiones a las prohibiciones previstas en la presente ley, dar\u00e1 lugar a la aplicaci\u00f3n de la sanci\u00f3n de multa equivalente a la unidad de valor adquisitivo (UVA) al momento de la sanci\u00f3n, de entre 500 y cien mil unidades de valor adquisitivo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cSer\u00e1 reprimido con prisi\u00f3n de tres (3) a diez (10) a\u00f1os el que explotare, administrare, operare o de cualquier manera organizare o administrare, por s\u00ed o a trav\u00e9s de terceros, cualquier modalidad o sistema de captaci\u00f3n de juegos de azar y apuestas, sin contar con la autorizaci\u00f3n jurisdiccional competente y el que facilitare sus datos biom\u00e9tricos, documentos, datos bancarios y\/o cualquier informaci\u00f3n que requiera el sitio web para participar del de apuestas\u201d, estipula el texto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por \u00faltimo, indica que cuando estas infracciones est\u00e9n dirigidas a menores 18 a\u00f1os de edad; la pena ser\u00e1 incrementada en un tercio del m\u00ednimo y del m\u00e1ximo, a\u00fan cuando exista autorizaci\u00f3n o licencia habilitante.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<strong>diputada Silvana Giudici (PRO)<\/strong>&nbsp;se refiri\u00f3 al dictamen de minor\u00eda que presentaron con apoyo de la UCR y LLA, al considerar que&nbsp;<strong>\u201cel otro dictamen es demasiado reglamentarista y extenso por lo cual se complica evaluar la constitucionalidad de la norma\u201d<\/strong>.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En ese sentido, hizo hincapi\u00e9 en los detalles de \u201csu dictamen simplificado\u201d: \u201cProhibimos la publicidad del juego en todas sus plataformas, pero no avanzamos en cuestiones que puedan limitar o lesionar otros derechos como la libertad de expresi\u00f3n y de contenidos en internet\u201d, dijo y agreg\u00f3: \u201cLo que hay que penar es al intermediario, a ese que junta el dinero de los chicos y luego hace apuestas m\u00e1s fuertes\u201d.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La posici\u00f3n de ALEA<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">En una carta con fecha 14 de noviembre, dirigida a los jefes de bloques mayoritarios de la C\u00e1mara de Diputados, desde la Asociaci\u00f3n de Loter\u00edas Estatales Argentinas (<a href=\"https:\/\/focusgn.com\/latinoamerica\/en-que-consiste-el-convenio-firmado-entre-la-asociacion-de-loterias-estatales-argentina-y-sedronar\" target=\"_blank\" rel=\"noreferrer noopener\">ALEA<\/a>)&nbsp;<a href=\"https:\/\/focusgn.com\/latinoamerica\/proyecto-contra-la-ciberludopatia-en-argentina-desde-alea-senalan-la-inconstitucionalidad-de-la-iniciativa-que-avanza-en-el-congreso\" target=\"_blank\" rel=\"noreferrer noopener\">explicaron que el proyecto es \u201cmanifiestamente inconstitucional<\/a>&nbsp;en la medida en que propicia un indebido avasallamiento del Honorable Congreso de la Naci\u00f3n sobre competencias que desde los albores mismos de la rep\u00fablica se han considerados como no delegadas a las provincias de la Naci\u00f3n\u201d, indica la misiva.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Para las autoridades de ALEA, la evidencia en distintos pa\u00edses ha demostrado que&nbsp;<strong>prohibir la publicidad no disminuye el juego ilegal<\/strong>. \u201cAl contrario, esta restricci\u00f3n puede generar un aumento en el acceso a plataformas no autorizadas, ya que al reducir la visibilidad de operadores legales y regulados, los usuarios pueden acceder a sitios que operan fuera del marco legal. Esto no solo afecta la seguridad de los jugadores, sino que tambi\u00e9n dificulta los esfuerzos de los entes reguladores para controlar la actividad\u201d, explicaron desde la asociaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, indicaron que \u201c<strong>la prohibici\u00f3n de la publicidad limita la posibilidad de informar sobre las herramientas de juego responsable<\/strong>, tales como los programas de autoexclusi\u00f3n y los canales de ayuda\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, agregaron que junto a la prohibici\u00f3n de patrocinios a entidades deportivas, provocar\u00e1 una \u201ccombinaci\u00f3n letal\u201d. \u201cNo solo se privar\u00e1 al p\u00fablico de informaci\u00f3n sobre la existencia de herramientas de juego responsable y canales de asistencia, sino que asimismo&nbsp;<strong>se desfinanciar\u00e1 a entidades que en su g\u00e9nesis procuran el desarrollo social<\/strong>\u201d, escribieron en la carta.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Asimismo, explicaron: \u201cUna lectura detallada del contenido del proyecto denota que la informaci\u00f3n y&nbsp;<a href=\"https:\/\/focusgn.com\/latinoamerica\/argentina-en-diputados-avanza-el-analisis-de-los-proyectos-sobre-ludopatia-infanto-juvenil\" target=\"_blank\" rel=\"noreferrer noopener\">evidencias presentadas oportunamente por ALEA han sido desestimadas<\/a>. Esto genera una muy honda preocupaci\u00f3n en el seno de ALEA al advertir que el proyecto implica un avasallamiento sobre las competencias propias de los miembros de ALEA, al mismo tiempo que, de aprobarse, agravar\u00e1 la situaci\u00f3n que pretende contener\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otra parte, las autoridades se pusieron a disposici\u00f3n de las comisiones para trabajar en conjunto en el texto de un proyecto que sea respetuoso de la Constituci\u00f3n Nacional y eficaz para lograr la limitaci\u00f3n del acceso de menores a productos nocivos.<\/p>\n\n\n\n<h2 class=\"wp-block-heading\">La presi\u00f3n de la Iglesia<\/h2>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp;<a href=\"https:\/\/focusgn.com\/latinoamerica\/la-iglesia-arremete-contra-el-juego-declaraciones-del-papa-y-carta-de-la-iglesia-catolica-argentina-a-diputados\" target=\"_blank\" rel=\"noreferrer noopener\">Iglesia Cat\u00f3lica envi\u00f3 una carta p\u00fablica<\/a>&nbsp;al presidente de la C\u00e1mara de Diputados, Mart\u00edn Menem, en la que reclama por un tratamiento urgente de la ley de prevenci\u00f3n de la ludopat\u00eda. Para eso, solicit\u00f3&nbsp;<strong>que se incluya en el temario de una sesi\u00f3n ya prevista o, por el contrario, se convoque a una sesi\u00f3n especial para avanzar con su debate en el recinto<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El mensaje de la Iglesia sostiene: \u201cConsideramos urgente que este dictamen reciba un pronto tratamiento en el recinto. Como bien lo han se\u00f1alado tanto legisladores de diversos bloques pol\u00edticos como representantes de organizaciones de la sociedad civil que participaron en las reuniones informativas, estamos ante un problema que exige una respuesta inmediata\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Uno de los focos de discusi\u00f3n en el que no se logra consenso es el de la publicidad de las casas de apuestas.<\/p>\n","protected":false},"author":226,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"Argentina se prepara para el inminente tratamiento de un proyecto de ley que busca regular el juego online, prevenir la ludopat\u00eda y, crucialmente, imponer severas restricciones a la publicidad y promoci\u00f3n de apuestas. La propuesta, que incluye la prohibici\u00f3n de bonos de bienvenida y patrocinios deportivos, as\u00ed como la verificaci\u00f3n biom\u00e9trica de identidad, enfrenta intensos debates legislativos, especialmente en torno a las limitaciones publicitarias.","focusai_entities":"Mart\u00edn Menem, M\u00f3nica Frade, Coalici\u00f3n C\u00edvica, Encuentro Federal, Radicales para Siempre, Uni\u00f3n por la Patria (UxP), La Libertad Avanza, PRO, UCR, Maximiliano Ferraro, Silvana Giudici","focusai_location":"Argentina","focusai_target_profile":"ceo_executive (1.0), regulator (1.0), compliance_legal (1.0), operator_casino (1.0), affiliate_publisher (1.0), product_ux (0.8), tech_data (0.8), marketing_crm (1.0), payments_fraud_aml (0.8), investor_analyst (1.0), supplier_vendor (0.7), journalist_researcher (1.0)","focusai_suggestions":[],"footnotes":""},"categories":[110,29,10],"tags":[41],"class_list":["post-777047966","post","type-post","status-publish","format-standard","hentry","category-legislacion","category-slider-home","category-sudamerica","tag-argentina"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777047966","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/226"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=777047966"}],"version-history":[{"count":4,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777047966\/revisions"}],"predecessor-version":[{"id":777048026,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777047966\/revisions\/777048026"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=777047966"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=777047966"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=777047966"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}