{"id":777034065,"date":"2024-05-22T10:55:55","date_gmt":"2024-05-22T13:55:55","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=777034065"},"modified":"2026-04-29T20:50:57","modified_gmt":"2026-04-29T23:50:57","slug":"diputados-brasilenos-debatiran-sobre-la-necesidad-de-innovacion-para-que-la-red-de-loterias-sea-sostenible","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/diputados-brasilenos-debatiran-sobre-la-necesidad-de-innovacion-para-que-la-red-de-loterias-sea-sostenible","title":{"rendered":"Diputados brasile\u00f1os debatir\u00e1n sobre la necesidad de innovaci\u00f3n para que la red de loter\u00edas sea sostenible"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La Comisi\u00f3n de Administraci\u00f3n y Servicio P\u00fablico de la C\u00e1mara de Diputados debate hoy la sostenibilidad de la red de loter\u00eda en Brasil.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Brasil.- La <strong>Comisi\u00f3n de Administraci\u00f3n y Servicio P\u00fablico<\/strong> de la C\u00e1mara de Diputados est\u00e1 convocada para debatir hoy la sostenibilidad de la red de loter\u00edas en Brasil. El debate fue solicitado por el diputado <strong>Reimont<\/strong>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abEs necesario retomar las discusiones y traer soluciones satisfactorias para la sostenibilidad de la red de loter\u00edas, que, a pesar de muchas innovaciones tecnol\u00f3gicas, sigue siendo el principal canal para bancarizar la inclusi\u00f3n social y atender a la poblaci\u00f3n, adem\u00e1s de su principal objetivo, que es el loter\u00eda federal\u00bb, afirma el parlamentario acerca de los motivos que lo llevaron a plantear esta discusi\u00f3n en el \u00e1mbito parlamentario.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El funcionario entiende que algunas situaciones necesitan ser debatidas y cita la inseguridad jur\u00eddica derivada de la precariedad del contrato de permiso; el desequilibrio econ\u00f3mico y financiero, resultante del rezago tarifario y la migraci\u00f3n del p\u00fablico al entorno digital; la falta de igualdad en la comercializaci\u00f3n de productos entre medios f\u00edsicos y digitales; y la necesidad de innovaci\u00f3n y reposicionamiento del mercado del segmento.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por estos motivos es que decidi\u00f3 que era necesario que se proceda al debate en comisi\u00f3n a fin de ver de qu\u00e9 manera pueden plantearse soluciones de innovaci\u00f3n para las loter\u00edas y que estas sean autosostenibles.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A fin de lograr sumar m\u00e1s elementos y testimonios al debate, los diputados convocaron a diferentes actores del sector. Hasta el momento, el \u00fanico confirmado es <strong>Bruno Lobato<\/strong>, presidente de <strong>ALSPI <\/strong>(Asociaci\u00f3n Nacional de Loter\u00edas, Corresponsales Bancarios y empresarios vinculados al juego).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Ver tambi\u00e9n: <\/strong><a href=\"https:\/\/focusgn.com\/latinoamerica\/caixa-economica-de-brasil-compartio-su-nueva-reglamentacion-de-los-permisos-de-loterias\" data-type=\"link\" data-id=\"https:\/\/focusgn.com\/latinoamerica\/caixa-economica-de-brasil-compartio-su-nueva-reglamentacion-de-los-permisos-de-loterias\" target=\"_blank\" rel=\"noreferrer noopener\">Caixa Econ\u00f4mica de Brasil comparti\u00f3 su nueva reglamentaci\u00f3n de los permisos de loter\u00edas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En tanto, Carlos Antonio Vieira Fernandes, presidente de <strong>Caixa Econ\u00f3mica Federal<\/strong>, y Jodismar Amaro, presidente de la Federaci\u00f3n Brasile\u00f1a de Empresas de Loter\u00eda (<strong>FEBRALOT<\/strong>), rechazaron la invitaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Quien a\u00fan no confirm\u00f3 su presencia es el ministro de Hacienda, <strong>Fernando Haddad<\/strong>, cuya presencia podr\u00eda dotar de mucha fuerza al debate y fijar posici\u00f3n gubernamental sobre la importancia de modernizar la red de loter\u00edas. El ministro quien no dio respuesta formal, ser\u00e1 esperado hasta \u00faltima hora en la reuni\u00f3n de hoy.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La Comisi\u00f3n de Administraci\u00f3n y Servicio P\u00fablico de la C\u00e1mara de Diputados debate hoy la sostenibilidad de la red de loter\u00eda en Brasil.<\/p>\n","protected":false},"author":680,"featured_media":77404,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"La C\u00e1mara de Diputados de Brasil debate la sostenibilidad de la red de loter\u00edas, abordando la inseguridad jur\u00eddica, el desequilibrio econ\u00f3mico por la migraci\u00f3n digital y la necesidad de innovaci\u00f3n. El diputado Reimont impuls\u00f3 la discusi\u00f3n, que cuenta con la participaci\u00f3n de ALSPI, mientras que representantes de Caixa Econ\u00f3mica Federal y FEBRALOT declinaron, y la presencia del Ministro de Hacienda, Fernando Haddad, est\u00e1 pendiente. El objetivo es encontrar soluciones para la autosostenibilidad y el rol de inclusi\u00f3n social de las loter\u00edas.","focusai_entities":"Reimont, Bruno Lobato, Carlos Antonio Vieira Fernandes, Jodismar Amaro, Fernando Haddad, Comisi\u00f3n de Administraci\u00f3n y Servicio P\u00fablico de la C\u00e1mara de Diputados, ALSPI (Asociaci\u00f3n Nacional de Loter\u00edas, Corresponsales Bancarios y empresarios vinculados al juego), Caixa Econ\u00f3mica Federal, FEBRALOT (Federaci\u00f3n Brasile\u00f1a de Empresas de Loter\u00eda)","focusai_location":"Brasil","focusai_target_profile":"ceo_executive (0.9), regulator (1.0), compliance_legal (0.9), operator_casino (0.85), product_ux (0.7), tech_data (0.7), marketing_crm (0.7), investor_analyst (0.9), supplier_vendor (0.85), journalist_researcher (0.95)","focusai_suggestions":[],"footnotes":""},"categories":[110,10],"tags":[25,32742],"class_list":["post-777034065","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislacion","category-sudamerica","tag-brasil","tag-loterias-en-brasil"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777034065","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/680"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=777034065"}],"version-history":[{"count":3,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777034065\/revisions"}],"predecessor-version":[{"id":777034122,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/777034065\/revisions\/777034122"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media\/77404"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=777034065"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=777034065"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=777034065"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}