{"id":54043,"date":"2020-10-15T04:09:43","date_gmt":"2020-10-15T07:09:43","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=54043"},"modified":"2020-10-15T10:53:08","modified_gmt":"2020-10-15T13:53:08","slug":"reabren-la-loteria-de-chubut-y-vuelven-los-sorteos","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/reabren-la-loteria-de-chubut-y-vuelven-los-sorteos","title":{"rendered":"Reabren la Loter\u00eda de Chubut y vuelven los sorteos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Tras el cierre por una alerta sobre un posible caso de Covid-19 entre los empleados, volvieron a abrir las oficinas y la sala de sorteos.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Argentina.- El presidente de Loter\u00eda del Chubut, Luis Mar\u00eda Aguirre, asegur\u00f3  que hoy volver\u00e1n a realizarse los sorteos de la Quiniela Provincial y La Poceada, tras el cierre de actividades por un posible caso de Covid-19. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Sin embargo, se establecer\u00e1n guardias m\u00ednimas de personal, para reducir las posibilidades de infecci\u00f3n en medio de la pandemia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan inform\u00f3, se reabrir\u00e1 tambi\u00e9n la Sala de Sorteos, en Rawson, luego de las tareas de desinfecci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Aguirre explic\u00f3 que durante el cierre, \u00abse desarroll\u00f3 un nuevo sistema de gesti\u00f3n que, ante el cierre de 48 horas que tuvimos que hacer, nos permiti\u00f3 realizar todas las tareas inherentes a los sorteos de quiniela de manera remota\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abDentro de la contingencia esto es muy bueno, porque todo lo que se realiza para que un sorteo se pueda llevar a cabo lo hicimos con cuatro o cinco personas y desde afuera de las oficinas del organismo y funcion\u00f3 muy bien\u00bb, detall\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El titular de Loter\u00eda del Chubut se\u00f1al\u00f3 que el extracto de la Loter\u00eda del Chubut hab\u00eda sido reemplazado, por 48 horas, por el de la provincia de R\u00edo Negro. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abAnte la contingencia, el sistema de gesti\u00f3n funcion\u00f3 muy bien y, aunque siempre quedan cosas para mejorar, pudimos realizar todas las tareas vinculadas con los sorteos desde fuera de la sede del organismo y de manera remota con cuatro o cinco personas. Se hizo un trabajo de automatizaci\u00f3n muy importante y todo lo vinculado a la captaci\u00f3n de apuestas y liquidaci\u00f3n de premios se efectu\u00f3 en l\u00ednea, desde fuera del Instituto de Asistencia Social\u00bb, explic\u00f3 Aguirre.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Tras el cierre por una alerta sobre un posible caso de Covid-19 entre los empleados, volvieron a abrir las oficinas y la sala de sorteos.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"","focusai_entities":"","focusai_location":"","focusai_target_profile":"","focusai_suggestions":[],"footnotes":""},"categories":[54,5,10],"tags":[41,1876],"class_list":["post-54043","post","type-post","status-publish","format-standard","hentry","category-negocios","category-noticias-diarias","category-sudamerica","tag-argentina","tag-sorteos"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/54043","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=54043"}],"version-history":[{"count":3,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/54043\/revisions"}],"predecessor-version":[{"id":54051,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/54043\/revisions\/54051"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=54043"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=54043"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=54043"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}