{"id":52074,"date":"2020-08-25T08:11:45","date_gmt":"2020-08-25T11:11:45","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=52074"},"modified":"2021-06-30T14:41:32","modified_gmt":"2021-06-30T17:41:32","slug":"peru-reclaman-por-la-situacion-de-casinos-y-tragamonedas","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/peru-reclaman-por-la-situacion-de-casinos-y-tragamonedas","title":{"rendered":"Per\u00fa: reclaman por la situaci\u00f3n de casinos y tragamonedas"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Mientras sigue sin autorizarse la reapertura de los casinos y tragamonedas, el sector reclama por una soluci\u00f3n ante la crisis que atraviesa.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Per\u00fa.- El presidente de la Sociedad Nacional de Juegos de Azar de Per\u00fa (SONAJA), Fernando Calder\u00f3n, levant\u00f3 la voz en nombre de las empresas del juego que <strong><em><a rel=\"noreferrer noopener\" href=\"https:\/\/focusgn.com\/latinoamerica\/sin-fecha-para-los-casinos-en-peru\" target=\"_blank\">llevan sin operar desde que se declar\u00f3 la pandemia del Covid-19 <\/a><\/em><\/strong>y las consecuentes medidas de confinamiento, en marzo pasado.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abLas 750 empresas dedicadas al negocio de los casinos y m\u00e1quinas tragamonedas, viven una profunda crisis sin soluci\u00f3n hasta el momento. No operan desde el 16 de marzo y tampoco pueden cambiar de giro de negocio por restricciones en su licencia\u00bb, expuso.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cA pesar de ser un sector 100% formal y de proveer 85 mil puestos de trabajo, los establecimientos de casinos y tragamonedas no han recibido el visto bueno de los planes reactivadores propuestos por el Gobierno\u201d, cuestion\u00f3 Calder\u00f3n y subray\u00f3 que la actividad repercute tambi\u00e9n en otros sectores: \u00abEl movimiento econ\u00f3mico dentro de un casino no solo est\u00e1 comprendiendo por los trabajadores, tambi\u00e9n existen otros giros de negocio internos como los proveedores de servicios, alimentos, incluso artistas que ahora no est\u00e1n realizando actividades. Sin embargo, las empresas siguen cumpliendo con sus obligaciones como pago de proveedores, servicios b\u00e1sicos, que han agravado la crisis\u00bb<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLo complicado para nuestra actividad fue ser excluida de Reactiva Per\u00fa. A pesar de que se hizo un esfuerzo por ingresar al Fae Turismo, porque nos encontramos dentro de la ley de turismo, solo se lograron beneficiar las micro y peque\u00f1as empresas\u201d, lament\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEstamos preparados para mantener protocolos de bioseguridad en los establecimientos cuando tengamos que reiniciar actividades\u201d, dijo y pidi\u00f3 apoyo al gobierno porque seg\u00fan revel\u00f3, muchos establecimientos pidieron pr\u00e9stamos bancarios para afrontar la crisis y no les fueron concedidos, por lo que hubo empresas que cerraron, dejando a muchos empleados sin trabajo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan explic\u00f3, el sector del juego tiene listo el protocolo e incluso fue aprobado por el Ministerio de Comercio Exterior y Turismo (Mincetur) y revisado por el Ministerio de Salud (Minsa).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cLas mesas van a funcionar con aforo limitado, ser\u00e1n tres personas respetando el distanciamiento social. Habr\u00e1 m\u00e1quinas tragamonedas apagadas, para que exista un distanciamiento entre los clientes\u201d, revel\u00f3. <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Mientras sigue sin autorizarse la reapertura de los casinos y tragamonedas, el sector reclama por una soluci\u00f3n ante la crisis que atraviesa.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"","focusai_entities":"","focusai_location":"","focusai_target_profile":"","focusai_suggestions":[],"footnotes":""},"categories":[19,29,10],"tags":[49,88],"class_list":["post-52074","post","type-post","status-publish","format-standard","hentry","category-casinos","category-slider-home","category-sudamerica","tag-casinos","tag-peru"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/52074","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=52074"}],"version-history":[{"count":4,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/52074\/revisions"}],"predecessor-version":[{"id":64991,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/52074\/revisions\/64991"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=52074"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=52074"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=52074"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}