{"id":51896,"date":"2020-08-19T09:25:39","date_gmt":"2020-08-19T12:25:39","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=51896"},"modified":"2020-08-19T10:48:58","modified_gmt":"2020-08-19T13:48:58","slug":"rio-negro-trabaja-en-la-licitacion-de-los-casinos","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/rio-negro-trabaja-en-la-licitacion-de-los-casinos","title":{"rendered":"R\u00edo Negro trabaja en la licitaci\u00f3n de los casinos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">La gobernadora llev\u00f3 tranquilidad a los trabajadores ante el proceso de licitaci\u00f3n para la explotaci\u00f3n de los casinos, que tardar\u00e1 tres meses.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Argentina.- Tres casinos que explotaba la empresa Entretenimientos Patagonia en <strong><em><a href=\"https:\/\/focusgn.com\/latinoamerica\/argentina-rio-negro-se-hace-cargo-de-tres-casinos\" target=\"_blank\" rel=\"noreferrer noopener\">R\u00edo Negro quedaron pendientes de licitaci\u00f3n<\/a><\/em><\/strong> tras la finalizaci\u00f3n del contrato de la compa\u00f1\u00eda con la provincia. El proceso podr\u00eda llevar tres meses, seg\u00fan dijo la gobernadora de R\u00edo Negro, Arabela Carreras, pero los puestos de trabajo est\u00e1n asegurados.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed lo confirm\u00f3 la mandataria en di\u00e1logo con la prensa rionegrina. \u00abNecesitamos al menos tres meses para hacer el nuevo llamado, para garantizar la transparencia que esperamos y los procesos administrativos que conlleva. Estamos definiendo el modelo por el cual se proteger\u00e1n las fuentes de trabajo de todos los trabajadores\u00bb, explic\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Entretenimientos Patagonia ten\u00eda la concesi\u00f3n de las salas de juego de Bariloche, El Bols\u00f3n e Ingeniero Jacobacci. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La gobernadora dijo que se decidi\u00f3 el llamado a licitaci\u00f3n, cuyo pliego est\u00e1 muy avanzado, \u00abpero requiere de un tiempo mayor a este mes\u00bb. Ante la duda de los trabajadores, asegur\u00f3 que tienen cubierto su salario a ra\u00edz del \u00faltimo pago de la empresa Entretenimientos Patagonia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Por otro lado, dijo que los bienes de los casinos se conservar\u00e1n y pasar\u00e1n a la Loter\u00eda de R\u00edo Negro. \u00abLa nueva licitaci\u00f3n contemplar\u00e1 una serie de bienes y un cupo de trabajadores deber\u00e1n ser contratados s\u00ed o s\u00ed por la nueva empresa que asuma la responsabilidad de explotar los casinos. Esta transici\u00f3n est\u00e1 en un proceso de definici\u00f3n en este momento y estamos decidiendo esa situaci\u00f3n intermedia\u00bb, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTenemos varias alternativas a seguir, queremos la m\u00e1s sencilla y la que mejor garantice la protecci\u00f3n de los derechos de los trabajadores. Para eso estamos en dialogo permanente con los dos gremios acreditados en la provincia y le transmitimos la tranquilidad de que se cobraran los salarios en tiempo y forma, y se conservaran las fuentes de trabajo\u00bb, dijo.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>La gobernadora llev\u00f3 tranquilidad a los trabajadores ante el proceso de licitaci\u00f3n para la explotaci\u00f3n de los casinos, que tardar\u00e1 tres meses.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"","focusai_entities":"","focusai_location":"","focusai_target_profile":"","focusai_suggestions":[],"footnotes":""},"categories":[19,10],"tags":[41,49,112],"class_list":["post-51896","post","type-post","status-publish","format-standard","hentry","category-casinos","category-sudamerica","tag-argentina","tag-casinos","tag-rio-negro"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/51896","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=51896"}],"version-history":[{"count":4,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/51896\/revisions"}],"predecessor-version":[{"id":51908,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/51896\/revisions\/51908"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=51896"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=51896"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=51896"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}