{"id":51737,"date":"2020-08-14T07:57:39","date_gmt":"2020-08-14T10:57:39","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=51737"},"modified":"2024-08-20T12:07:16","modified_gmt":"2024-08-20T15:07:16","slug":"buenos-aires-busca-autorizar-apuestas-online","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/buenos-aires-busca-autorizar-apuestas-online","title":{"rendered":"Buenos Aires busca autorizar apuestas online"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">El gobierno de la Ciudad de Buenos Aires busca que el Hip\u00f3dromo de Palermo y el Casino de Puerto Madero se sumen a las apuestas online.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Argentina.- El Gobierno porte\u00f1o busca compensar el cierre del <strong><em>Hip\u00f3dromo de Palermo<\/em><\/strong> y del Casino de Puerto Madero ofreciendo la posibilidad de sumarse a la modalidad online.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La intenci\u00f3n, seg\u00fan publica el diario <strong><em>Clar\u00edn<\/em><\/strong>, es modificar la normativa vigente para permitir a estos dos establecimientos sumarse al negocio online, con el que el Estado espera recaudar alrededor de US$6.8 millones en impuestos.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Adem\u00e1s, el gobierno porte\u00f1o busca que, junto con los cambios para permitir el ingreso del Hip\u00f3dromo y el Casino Flotante,&nbsp;se vote una ley para prevenir la ludopat\u00eda&nbsp;en territorio porte\u00f1o. Las medidas limitar\u00edan la publicidad del juego, para evitar que los adolescentes tomen contacto con la actividad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La aprobaci\u00f3n de las apuestas online en la Ciudad de Buenos Aires est\u00e1 en proceso desde fines del 2018, cuando la Legislatura porte\u00f1a autoriz\u00f3 la operaci\u00f3n de las casas de juego online.&nbsp;En mayo del 2019 se aprob\u00f3 la reglamentaci\u00f3n.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En febrero de este a\u00f1o, la Loter\u00eda de la Ciudad de Buenos Aires (LOTBA) abri\u00f3 una convocatoria para que se presentaran los interesados que, hasta el momento, son seis grupos empresarios.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>El gobierno de la Ciudad de Buenos Aires busca que el Hip\u00f3dromo de Palermo y el Casino de Puerto Madero se sumen a las apuestas online.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"","focusai_entities":"","focusai_location":"","focusai_target_profile":"","focusai_suggestions":[],"footnotes":""},"categories":[110,29,10],"tags":[73,41,503],"class_list":["post-51737","post","type-post","status-publish","format-standard","hentry","category-legislacion","category-slider-home","category-sudamerica","tag-apuestas-deportivas","tag-argentina","tag-legislacion"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/51737","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=51737"}],"version-history":[{"count":8,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/51737\/revisions"}],"predecessor-version":[{"id":777040510,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/51737\/revisions\/777040510"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=51737"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=51737"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=51737"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}