{"id":51226,"date":"2020-07-31T05:54:25","date_gmt":"2020-07-31T08:54:25","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=51226"},"modified":"2020-07-31T10:56:01","modified_gmt":"2020-07-31T13:56:01","slug":"la-pampa-casinos-realizaron-donaciones","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/la-pampa-casinos-realizaron-donaciones","title":{"rendered":"La Pampa: casinos realizaron donaciones"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Dos casinos de La Pampa realizaron donaciones solidarias a un merendero de Santa Rosa, en medio de la crisis por la pandemia del Covid-19.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Argentina.- Los casinos de La Pampa Hotel Mercure y Casino Club realizaron donaciones a una instituci\u00f3n en el marco de la pandemia del Covid-19.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Las compa\u00f1\u00edas de juegos donaron alimentos para 60 ni\u00f1os y 15 familias del merendero Todo de Coraz\u00f3n, ubicado en el barrio Escondido de la ciudad de Santa Rosa.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La donaci\u00f3n fue parte de la iniciativa Mundo Club, que activ\u00f3 una serie de acciones para ayudar a los que menos tienen en plena crisis econ\u00f3mica.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cDurante la \u00faltima semana el Gerente de Casino Club, Marcelo Moya y el Sub Gerente Mariano Videla se acercaron al barrio escondido para entregar 60 kg de arroz, 90 kg de fideos (180 paquetes), 16 kg de polenta, 40kg de salsa de tomate, 10 kg de carne picada y 60 kg de pollo. Tambi\u00e9n, colaboraron con 100 porciones de Arroz con leche que fueron entregadas en el almuerzo del d\u00eda siguiente\u201d, se inform\u00f3 desde Mundo Club.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cTeniendo en cuenta el contexto actual, el alimento es algo muy necesario en estos tiempos, ya que los problemas y dificultades aparecen todos los d\u00edas y a toda hora, es por ello, que el objetivo de la empresa se sintetiza en una palabra: Ayudar. Tambi\u00e9n, en el comedor se preparan todos los s\u00e1bados comida para los m\u00e1s necesitados, las encargadas son las Madres Luchadoras de Koriza que, a su vez, realizan estas actividades todas las semanas para entretener a los m\u00e1s chicos y brindarles apoyo a sus familias\u201d, dijeron los organizadores.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cEn el contexto previo a la pandemia el panorama ya era cr\u00edtico, es por eso que desde Casino Club y Hotel Mercure queremos brindar nuestro apoyo a todos aquellos que no tienen esas posibilidades, ahora el desaf\u00edo se multiplic\u00f3 y habr\u00e1 que redoblar los esfuerzos para asegurarse que a ninguna familia le falte la comida en la mesa\u201d, concluyeron.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Dos casinos de La Pampa realizaron donaciones solidarias a un merendero de Santa Rosa, en medio de la crisis por la pandemia del Covid-19.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"","focusai_entities":"","focusai_location":"","focusai_target_profile":"","focusai_suggestions":[],"footnotes":""},"categories":[19,10],"tags":[41,49],"class_list":["post-51226","post","type-post","status-publish","format-standard","hentry","category-casinos","category-sudamerica","tag-argentina","tag-casinos"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/51226","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=51226"}],"version-history":[{"count":3,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/51226\/revisions"}],"predecessor-version":[{"id":51229,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/51226\/revisions\/51229"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=51226"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=51226"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=51226"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}