{"id":43204,"date":"2019-10-21T11:11:25","date_gmt":"2019-10-21T14:11:25","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=43204"},"modified":"2019-10-21T11:14:28","modified_gmt":"2019-10-21T14:14:28","slug":"google-publicidad-apuestas","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/google-publicidad-apuestas","title":{"rendered":"Google permite la publicidad de apuestas en Estados Unidos"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Google autoriz\u00f3 a cinco estados a realizar publicidad sobre apuestas, ya que actualiz\u00f3 sus pol\u00edticas.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Estados Unidos.- La industria de las apuestas deportivas est\u00e1 evolucionando en los Estados Unidos. Pero todav\u00eda hay cosas que deben actualizarse para que pueda prosperar el sector. Es por eso que <strong><em><a href=\"https:\/\/www.google.com\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\">Google<\/a><\/em><\/strong> ahora permite que cinco estados anuncien juegos de apuestas actualizando sus pol\u00edticas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La compa\u00f1\u00eda cambi\u00f3 su pol\u00edtica de juegos y apuestas en Pennsylvania, Rhode Island, Montana, Iowa e Indiana. Siguen a Nueva Jersey, Nevada y Virginia Occidental. As\u00ed, Google lanz\u00f3 un programa para mantenerse al d\u00eda con las <strong><em><a href=\"https:\/\/focusgn.com\/latinoamerica\/aga-apuestas-deportivas-estados-unidos\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\">apuestas deportivas<\/a><\/em><\/strong> en los Estados Unidos. Y las empresas tendr\u00e1n permiso para hacer publicidad.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Las apuestas deportivas florecen en Pensilvania<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La Junta de Control de Juegos de Pensilvania (PGCB) ha publicado el <strong><em><a href=\"https:\/\/focusgn.com\/latinoamerica\/apuestas-deportivas-millones-estados-unidos-juegos\" target=\"_blank\" rel=\"noreferrer noopener\" aria-label=\" (abre en una nueva pesta\u00f1a)\">informe financiero<\/a><\/em><\/strong> de septiembre de 2019. De agosto a septiembre, los ingresos de las apuestas deportivas aumentaron en un 144%. Mientras que los juegos en general aumentaron un 5% desde 2018 en Pensilvania<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan uno de los cuatro nuevos informes de ingresos de la PGCB, los ingresos totales de las casas de apuestas minoristas y en l\u00ednea totalizaron US$14.9 millones, que es 144.1% m\u00e1s que lo alcanzado en agosto (US$6.1 millones).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">El regulador del juego tambi\u00e9n dijo que el manejo a trav\u00e9s del comercio minorista y en l\u00ednea totaliz\u00f3 US$194 millones en septiembre. Esa cifra tambi\u00e9n es 78.4% m\u00e1s alta que la de agosto, cuando el estado recibi\u00f3 US$109 millones en apuestas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Valley Forge Casino fue el operador l\u00edder en septiembre, recaudando US$5.1 millones en ingresos combinados y US$88 millones en total. El total de SugarHouse Casino fue de US$37 millones, mientras que los ingresos generales fueron de US$2.9 millones.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Google autoriz\u00f3 a cinco estados a realizar publicidad sobre apuestas, ya que actualiz\u00f3 sus pol\u00edticas.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"","focusai_entities":"","focusai_location":"","focusai_target_profile":"","focusai_suggestions":[],"footnotes":""},"categories":[17979,22],"tags":[73,20],"class_list":["post-43204","post","type-post","status-publish","format-standard","hentry","category-apuestas-deportivas","category-norte-america","tag-apuestas-deportivas","tag-estados-unidos"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/43204","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=43204"}],"version-history":[{"count":1,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/43204\/revisions"}],"predecessor-version":[{"id":43218,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/43204\/revisions\/43218"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=43204"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=43204"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=43204"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}