{"id":42542,"date":"2019-09-26T08:25:26","date_gmt":"2019-09-26T11:25:26","guid":{"rendered":"https:\/\/focusgn.com\/latinoamerica\/?p=42542"},"modified":"2023-08-28T11:49:29","modified_gmt":"2023-08-28T14:49:29","slug":"ventas-casinos-tenerife-apuestas","status":"publish","type":"post","link":"https:\/\/focusgn.com\/latinoamerica\/ventas-casinos-tenerife-apuestas","title":{"rendered":"Nuevas reacciones sobre Casinos de Tenerife"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\"> La fallida venta de los tres Casinos de Tenerife gener\u00f3 diversas reacciones y la m\u00e1s reciente fue la del CC-PNC, que dispar\u00f3 contra el gobierno. <\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Espa\u00f1a.- El gobierno canario no consigui\u00f3 vender la sociedad Casinos de Tenerife y sus tres salas. Con la licitaci\u00f3n vacante, distintos sectores pol\u00edticos tuvieron diferentes reacciones al respecto.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">As\u00ed, el grupo Nacionalista Canario (CC-PNC) dispar\u00f3 contra el gobierno por abandonar la venta. Adem\u00e1s, fue sumamente duro con Enrique Arriaga y Concepci\u00f3n Rivero, a quienes calificaron de \u201ctr\u00e1nsfugas\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan CC-PNC, los consejeros que se mudaron de partido, actuaron contra lo que hab\u00edan prometido. Para CC-PNC, el PSOE va \u00abcontra sus propios actos para contentar a S\u00ed Podemos Canarias\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acuerdo al partido, s\u00ed hay una empresa interesada en la compra y cumple todos los requisitos. Sin embargo, el gobierno \u00abalude a una cl\u00e1usula del pliego para decir que no se puede culminar el proceso\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Licitaci\u00f3n desierta<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La venta de los tres casinos estatales de Tenerife no para de cruzarse con malas noticias. Entre conflictos legales y cr\u00edticas, el concurso (iniciado en 2016) no tuvo \u00e9xito y la licitaci\u00f3n <a href=\"https:\/\/focusgn.com\/latinoamerica\/venta-casinos-tenerife-apuestas\"><strong><em>qued\u00f3 desierta<\/em><\/strong><\/a>.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Si bien falta que el Consejo de Gobierno adopte la decisi\u00f3n, la Mesa de Contrataci\u00f3n proclam\u00f3 el resultado del concurso. Presumen que la inversi\u00f3n de US$4.9 millones requerida en <strong><em>turismo<\/em><\/strong> para quedarse las salas trab\u00f3 la venta.\u00a0<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Festejos<\/strong><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">La&nbsp; portavoz de S\u00ed Podemos, Mar\u00eda Jos\u00e9 Belda, lo calific\u00f3 como \u201cuna victoria y una gran noticia para las m\u00e1s de 150 personas trabajadoras de Casinos de Tenerife y sus familias\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Seg\u00fan Belda, Casinos de Tenerife es \u00abaltamente rentable para las arcas p\u00fablicas de este Cabildo. Por consiguiente, repercute en la mejora de la calidad de vida de nuestra sociedad\u201d.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201cHemos luchado y criticado la intenci\u00f3n de CC, PP y PSOE de querer privatizar dicha empresa p\u00fablica. No hab\u00eda justificaci\u00f3n alguna por la que fuera necesario llevar a cabo este proceso de venta, al que desde el anterior grupo nos opusimos desde 2016\u2033.<br><\/p>\n","protected":false},"excerpt":{"rendered":"<p>La fallida venta de los tres Casinos de Tenerife gener\u00f3 diversas reacciones y la m\u00e1s reciente fue la del CC-PNC, que dispar\u00f3 contra el gobierno.<\/p>\n","protected":false},"author":174,"featured_media":0,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"","focusai_entities":"","focusai_location":"","focusai_target_profile":"","focusai_suggestions":[],"footnotes":""},"categories":[19,2,5,55,37590],"tags":[49,11],"class_list":["post-42542","post","type-post","status-publish","format-standard","hentry","category-casinos","category-emea","category-noticias-diarias","category-noticias-por-region","category-otras-regiones","tag-casinos","tag-espana"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/42542","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/users\/174"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/comments?post=42542"}],"version-history":[{"count":2,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/42542\/revisions"}],"predecessor-version":[{"id":777015887,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/posts\/42542\/revisions\/777015887"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/media?parent=42542"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/categories?post=42542"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/latinoamerica\/wp-json\/wp\/v2\/tags?post=42542"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}