{"id":58871,"date":"2026-09-02T07:20:21","date_gmt":"2026-09-02T10:20:21","guid":{"rendered":"https:\/\/focusgn.com\/brasil\/?p=58871"},"modified":"2026-09-02T07:21:38","modified_gmt":"2026-09-02T10:21:38","slug":"impactos-das-bets-e-tema-de-audiencia-na-comissao-de-ciencia-e-tecnologia-do-senado","status":"publish","type":"post","link":"https:\/\/focusgn.com\/brasil\/impactos-das-bets-e-tema-de-audiencia-na-comissao-de-ciencia-e-tecnologia-do-senado","title":{"rendered":"Senado discute impactos das bets em audi\u00eancia p\u00fablica"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Entre os temas abordados, esteve a possibilidade de aplicar restri\u00e7\u00f5es \u00e0 publicidade das apostas.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">Bras\u00edlia.- A <strong>Comiss\u00e3o de Ci\u00eancia e Tecnologia do Senado (CCT<\/strong>) promoveu uma audi\u00eancia p\u00fablica na ter\u00e7a (1\u00ba). O evento teve o objetivo de <strong>discutir os impactos das empresas de apostas de quota fixa para a sa\u00fade mental e a economia das fam\u00edlias <\/strong>brasileiras. Tamb\u00e9m esteve na pauta do debate, o <strong>Projeto de Lei N\u00ba 2.470\/2026<\/strong>, que visa restringir a publicidade do setor de igaming.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Segundo o que publicou a Ag\u00eancia Senado, a discuss\u00e3o buscou contribuir com a avalia\u00e7\u00e3o do projeto de lei, que \u00e9 de autoria da senadora <a href=\"https:\/\/focusgn.com\/brasil\/entenda-porque-uma-bancada-suprapartidaria-do-congresso-quer-definir-as-bets-como-risco-a-saude-publica\" target=\"_blank\" rel=\"noreferrer noopener\">Damares Alves<\/a> (Republicanos-DF) em parceria com outros senadores: Izalci Lucas (PL-DF), Hamilton Mour\u00e3o (Republicanos-RS), Astronauta Marcos Pontes (PL-SP), Teresa Leit\u00e3o (PT-PE), Humberto Costa (PT-PE), Otto Alencar (PSD-BA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Veja tamb\u00e9m:<\/strong> <a href=\"https:\/\/focusgn.com\/brasil\/projeto-na-camara-propoe-assistencia-a-familiares-afetados-por-problemas-com-apostas\" target=\"_blank\" rel=\"noreferrer noopener\">Projeto na C\u00e2mara prop\u00f5e assist\u00eancia a familiares afetados por problemas com apostas<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A proposta tem a inten\u00e7\u00e3o de estabelecer medidas para proteger grupos vulner\u00e1veis ao reduzir a publicidade de apostas, incluindo patroc\u00ednios desse setor. O relator do Projeto de Lei N\u00ba 2.470\/2026 o senador&nbsp;<strong>Alessandro Vieira<\/strong> (MDB-SE), comentou sobre a urg\u00eancia da mat\u00e9ria para o pa\u00eds.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;Est\u00e1 claro e evidente que n\u00f3s temos muito a conversar, a trabalhar em cima dele, mas a expectativa \u00e9 que possamos j\u00e1 amanh\u00e3 [quarta-feira (2)] apresentar uma primeira vers\u00e3o de relat\u00f3rio para que esse projeto possa avan\u00e7ar&#8221;, disse Vieira.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Damares Alves comentou sobre as t\u00e9cnicas usadas pelas bets para atrair usu\u00e1rios. &#8220;Eles colocam de uma forma t\u00e3o rom\u00e2ntica: &#8220;Jogo respons\u00e1vel.&nbsp;N\u00e3o \u00e9 jogo respons\u00e1vel; \u00e9 jogo de azar, \u00e9 perda respons\u00e1vel&#8221;, criticou a senadora.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Os parlamentares convidaram para a audi\u00eancia <strong>Marcelo Kimati Dias<\/strong>, diretor do Departamento de Sa\u00fade Mental, \u00c1lcool e Outras Drogas do <strong>Minist\u00e9rio da Sa\u00fade<\/strong>. Segundo o representante da pasta, no ano passado, cerca de 25 milh\u00f5es de brasileiros apostaram em plataformas legalizadas e uma parcela desses usu\u00e1rios teria desenvolvido transtornos relacionados ao jogo.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Representando o mercado regulado de apostas, <a href=\"https:\/\/focusgn.com\/brasil\/saiba-quem-e-o-novo-presidente-executivo-do-instituto-brasileiro-de-jogo-responsavel\" target=\"_blank\" rel=\"noreferrer noopener\">Carlos Lima<\/a>, presidente executivo do <a href=\"https:\/\/focusgn.com\/brasil\/apostas-ilegais-percentual-cai-no-brasil-mas-ainda-atinge-metade-dos-apostadores\" target=\"_blank\" rel=\"noreferrer noopener\">Instituto Brasileiro de Jogo Respons\u00e1vel (IBJR)<\/a>, tamb\u00e9m esteve presente. O executivo apresentou dados de um estudo promovido pela Aliciar Consultoria, que indica que o endividamento da popula\u00e7\u00e3o brasileira ocorre por conta de outros fatores, com as apostas estando em \u00faltimo lugar na lista apresentada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">&#8220;\u00c9 um setor que hoje representa R$ 9,6 bilh\u00f5es (US$ 1,8 bilh\u00e3o) de arrecada\u00e7\u00e3o para o pa\u00eds e que gera mais de 15,5 mil empregos diretos e indiretos. \u00c9 um setor que colabora com contribui\u00e7\u00f5es sociais para o esporte, servi\u00e7os de sa\u00fade, enfim. E \u00e9 um setor que tem faturamento bruto de R$ 35 bilh\u00f5es (US$ 6,8 bilh\u00f5es)&#8221;, disse Lima.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O presidente do IBJR afirmou ainda que o principal desafio do setor \u00e9 combater as plataformas clandestinas. Lima explicou que as casas de apostas regulamentadas possuem mecanismos de verifica\u00e7\u00e3o de identidade, limites de apostas e ferramentas de prote\u00e7\u00e3o que n\u00e3o existem em plataformas ilegais.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Entre os temas abordados, esteve a possibilidade de aplicar restri\u00e7\u00f5es \u00e0 publicidade das apostas.<\/p>\n","protected":false},"author":689,"featured_media":58877,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"A Comiss\u00e3o de Ci\u00eancia e Tecnologia do Senado brasileiro realizou uma audi\u00eancia p\u00fablica para debater os impactos sociais e econ\u00f4micos das empresas de apostas de quota fixa, focando na sa\u00fade mental e no endividamento familiar. O evento discutiu o Projeto de Lei N\u00ba 2.470\/2026, que prop\u00f5e restri\u00e7\u00f5es \u00e0 publicidade do setor de iGaming, com a participa\u00e7\u00e3o de legisladores, representantes do Minist\u00e9rio da Sa\u00fade e do Instituto Brasileiro de Jogo Respons\u00e1vel (IBJR). O debate abordou a necessidade de proteger grupos vulner\u00e1veis, o combate a plataformas clandestinas e a contribui\u00e7\u00e3o econ\u00f4mica do setor regulado, que gera R$ 9,6 bilh\u00f5es em arrecada\u00e7\u00e3o e R$ 35 bilh\u00f5es em faturamento bruto.","focusai_entities":"Comiss\u00e3o de Ci\u00eancia e Tecnologia do Senado (CCT), Senado, Damares Alves, Republicanos-DF, Izalci Lucas, PL-DF, Hamilton Mour\u00e3o, Republicanos-RS, Astronauta Marcos Pontes, PL-SP, Teresa Leit\u00e3o, PT-PE, Humberto Costa, PT-PE, Otto Alencar, PSD-BA, Alessandro Vieira, MDB-SE, Marcelo Kimati Dias, Departamento de Sa\u00fade Mental, \u00c1lcool e Outras Drogas do Minist\u00e9rio da Sa\u00fade, Minist\u00e9rio da Sa\u00fade, Carlos Lima, Instituto Brasileiro de Jogo Respons\u00e1vel (IBJR), Aliciar Consultoria","focusai_location":"Bras\u00edlia, Brasil","focusai_target_profile":"ceo_executive (0.9), regulator (1.0), compliance_legal (1.0), operator_casino (0.9), affiliate_publisher (0.9), product_ux (0.7), marketing_crm (1.0), payments_fraud_aml (0.7), investor_analyst (0.9), supplier_vendor (0.7), journalist_researcher (1.0)","focusai_suggestions":[{"label":"Impacto Restri\u00e7\u00f5es Publicit\u00e1rias?","query":"Quais s\u00e3o as proje\u00e7\u00f5es de impacto financeiro e de aquisi\u00e7\u00e3o de clientes para os operadores regulamentados no Brasil caso o Projeto de Lei N\u00ba 2.470\/2026 seja aprovado com as restri\u00e7\u00f5es propostas \u00e0 publicidade?"},{"label":"Estrat\u00e9gias Contra Ilegales?","query":"Que medidas adicionais o governo e o setor regulado planejam implementar para combater eficazmente as plataformas clandestinas, dado o seu impacto na sa\u00fade mental e na arrecada\u00e7\u00e3o fiscal?"}],"footnotes":""},"categories":[28,22],"tags":[47,45,64],"class_list":["post-58871","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-legislacao","category-central-oeste","tag-igaming","tag-industria-de-jogos","tag-regulamentacao-do-jogo"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/posts\/58871","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/users\/689"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/comments?post=58871"}],"version-history":[{"count":11,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/posts\/58871\/revisions"}],"predecessor-version":[{"id":58903,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/posts\/58871\/revisions\/58903"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/media\/58877"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/media?parent=58871"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/categories?post=58871"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/tags?post=58871"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}