{"id":11283,"date":"2024-03-04T07:34:42","date_gmt":"2024-03-04T10:34:42","guid":{"rendered":"https:\/\/focusgn.com\/brasil\/?p=11283"},"modified":"2026-04-21T03:17:10","modified_gmt":"2026-04-21T06:17:10","slug":"falcao-o-rei-do-futsal-estreia-no-futebol-de-varzea-em-competicao-patrocinada-pela-f12-bet","status":"publish","type":"post","link":"https:\/\/focusgn.com\/brasil\/falcao-o-rei-do-futsal-estreia-no-futebol-de-varzea-em-competicao-patrocinada-pela-f12-bet","title":{"rendered":"Falc\u00e3o, o &#8220;Rei do Futsal&#8221;, estreia no futebol de v\u00e1rzea em competi\u00e7\u00e3o patrocinada pela F12.Bet"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Atleta saiu da aposentadoria para competir por time pr\u00f3prio.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">S\u00e3o Paulo.- Alessandro Vieira, o <strong>Falc\u00e3o<\/strong>, \u00e9 considerado por muitos como o &#8220;<strong>Rei do Futsal<\/strong>&#8221; por conta das diversas conquistas por clubes e Sele\u00e7\u00e3o Brasileira, al\u00e9m de quatro pr\u00eamios de melhor jogador do mundo da modalidade. Agora como empres\u00e1rio, o ex-atleta lan\u00e7ou um time de futebol de v\u00e1rzea na cidade de <strong>S\u00e3o Paulo<\/strong>, o <strong>Reinado Futebol Clube<\/strong>.  <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nova equipe de Falc\u00e3o, que ter\u00e1 o refor\u00e7o do pr\u00f3prio &#8220;Rei&#8221; integrando o time aos 46 anos, j\u00e1 tem um desafio previsto, a <strong>Copa Nove de Julho<\/strong>, uma tradicional competi\u00e7\u00e3o de futebol de v\u00e1rzea. A copa \u00e9 patrocinada pela <strong>casa de apostas esportivas e cassino online F12.Bet<\/strong>, que tem o ex-jogador de futsal como s\u00f3cio. A estreia da equipe na competi\u00e7\u00e3o foi no \u00faltimo s\u00e1bado (2).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Al\u00e9m da Copa Nove de Julho, a F12.Bet patrocina outros campeonatos de v\u00e1rzea, como a <strong>Super Copa Pioneer<\/strong>, <strong>Copa da Paz<\/strong>, <strong>Copa do Bus\u00e3o<\/strong>, <strong>Copa Anhanguera<\/strong>, <strong>Copa Macaco Louco<\/strong>, <strong>Negritude<\/strong>, <strong>Savime<\/strong>, <strong>Doroteia<\/strong>, <strong>Regina<\/strong> e <strong>Xdomorro<\/strong>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Atleta saiu da aposentadoria para competir por time pr\u00f3prio.<\/p>\n","protected":false},"author":689,"featured_media":11289,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"is_press_release":false,"is_interview":false,"is_opinion":false,"focusai_summary":"Alessandro Vieira, conhecido como Falc\u00e3o, lan\u00e7ou o Reinado Futebol Clube, uma equipe de futebol de v\u00e1rzea em S\u00e3o Paulo, na qual ele pr\u00f3prio competir\u00e1. A equipe estreou na Copa Nove de Julho, um torneio patrocinado pela F12.Bet, casa de apostas esportivas e cassino online da qual Falc\u00e3o \u00e9 s\u00f3cio, que tamb\u00e9m patrocina diversas outras competi\u00e7\u00f5es de v\u00e1rzea.","focusai_entities":"Alessandro Vieira (Falc\u00e3o), Reinado Futebol Clube, F12.Bet, Copa Nove de Julho, Super Copa Pioneer, Copa da Paz, Copa do Bus\u00e3o, Copa Anhanguera, Copa Macaco Louco, Negritude, Savime, Doroteia, Regina, Xdomorro","focusai_location":"S\u00e3o Paulo","focusai_target_profile":"ceo_executive (0.9), operator_casino (0.9), affiliate_publisher (0.7), marketing_crm (0.9), investor_analyst (0.7), journalist_researcher (0.8)","focusai_suggestions":[{"label":"ROI do Patroc\u00ednio F12.Bet?","query":"Qual o ROI esperado pela F12.Bet com o patroc\u00ednio de torneios de v\u00e1rzea e a associa\u00e7\u00e3o com Falc\u00e3o, considerando o custo de aquisi\u00e7\u00e3o de clientes (CAC) no mercado brasileiro?"},{"label":"Estrat\u00e9gia de Marketing no Brasil?","query":"Como esta estrat\u00e9gia de marketing de base se alinha com a penetra\u00e7\u00e3o da F12.Bet em mercados regulados ou em processo de regula\u00e7\u00e3o no Brasil, e quais os riscos e oportunidades associados?"}],"footnotes":""},"categories":[27,23],"tags":[43,101],"class_list":["post-11283","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-apostas-esportivas","category-sudeste","tag-apostas-esportivas","tag-futebol"],"_links":{"self":[{"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/posts\/11283","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/users\/689"}],"replies":[{"embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/comments?post=11283"}],"version-history":[{"count":8,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/posts\/11283\/revisions"}],"predecessor-version":[{"id":11304,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/posts\/11283\/revisions\/11304"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/media\/11289"}],"wp:attachment":[{"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/media?parent=11283"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/categories?post=11283"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/focusgn.com\/brasil\/wp-json\/wp\/v2\/tags?post=11283"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}